{"id":4190,"date":"2021-09-08T20:13:39","date_gmt":"2021-09-08T20:13:39","guid":{"rendered":"https:\/\/darkseagreen-bear-454432.hostingersite.com\/studio\/"},"modified":"2025-11-04T09:27:35","modified_gmt":"2025-11-04T09:27:35","slug":"studio","status":"publish","type":"page","link":"https:\/\/lilyfit.com\/sr\/studio\/","title":{"rendered":"Studio"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; background_image=&#8220;https:\/\/lilyfit.com\/wp-content\/uploads\/2024\/08\/slide-2.jpg&#8220; background_position=&#8220;top_center&#8220; height=&#8220;568px&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; background_enable_image=&#8220;off&#8220; width=&#8220;1920px&#8220; max_width=&#8220;90%&#8220; height=&#8220;568px&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin: auto&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin: auto;||padding-top: 300px;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;||||||||&#8220; text_font_size=&#8220;40px&#8220; text_line_height=&#8220;1.4em&#8220; header_font_size=&#8220;78px&#8220; header_4_font_size=&#8220;28px&#8220; custom_margin=&#8220;||0.5em||false|false&#8220; custom_padding=&#8220;||||false|false&#8220; text_font_size_tablet=&#8220;&#8220; text_font_size_phone=&#8220;32px&#8220; text_font_size_last_edited=&#8220;on|phone&#8220; header_font_size_tablet=&#8220;45px&#8220; header_font_size_phone=&#8220;30px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_4_font_size_tablet=&#8220;24px&#8220; header_4_font_size_phone=&#8220;20px&#8220; header_4_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div style=\"text-transform: uppercase; color: white; text-align: center;\">Dobrodo\u0161li u pilates studio lilyfit<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=&#8220;#contemporary-boutique&#8220; button_text=&#8220;Saznaj vi\u0161e&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;25px&#8220; button_text_color=&#8220;#FFFFFF&#8220; button_border_radius=&#8220;12px&#8220; button_font=&#8220;|||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_padding=&#8220;8px|22px|8px|22px|true|true&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|hover&#8220; button_bg_color__hover=&#8220;#000000&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_width__hover_enabled=&#8220;off|hover&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#000000&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; module_id=&#8220;contemporary-boutique&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;10px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Gotham-Book|500|||||||&#8220; header_font_size=&#8220;44px&#8220; header_line_height=&#8220;1.2em&#8220; custom_margin=&#8220;15px||15px||true|false&#8220; custom_margin_tablet=&#8220;12px||12px||true|false&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;38px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\">Prvi Klasi\u010dni Pilates Studio u Beogradu<\/h1>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#aac6be&#8220; divider_weight=&#8220;8px&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;350px&#8220; max_width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;https:\/\/darkseagreen-bear-454432.hostingersite.com\/pricing\/#private-sessions&#8220; button_text=&#8220;Cene&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;25px&#8220; button_text_color=&#8220;#000000&#8243; button_border_radius=&#8220;12px&#8220; button_font=&#8220;|||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_padding=&#8220;8px|22px|8px|22px|true|true&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|desktop&#8220; button_bg_color__hover=&#8220;#000000&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_width__hover_enabled=&#8220;off|hover&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#000000&#8243; button_text_color__hover_enabled=&#8220;on|hover&#8220; button_text_color__hover=&#8220;#FFFFFF&#8220;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_button button_url=&#8220;https:\/\/darkseagreen-bear-454432.hostingersite.com\/sr\/?page_id=4128&#8243; button_text=&#8220;Rezervi\u0161i \u010das&#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;25px&#8220; button_text_color=&#8220;#000000&#8243; button_border_radius=&#8220;12px&#8220; button_font=&#8220;|||on|||||&#8220; button_use_icon=&#8220;off&#8220; custom_padding=&#8220;8px|22px|8px|22px|true|true&#8220; global_colors_info=&#8220;{}&#8220; button_bg_color__hover_enabled=&#8220;on|desktop&#8220; button_bg_color__hover=&#8220;#000000&#8243; button_bg_enable_color__hover=&#8220;on&#8220; button_border_width__hover_enabled=&#8220;off|hover&#8220; button_border_color__hover_enabled=&#8220;on|hover&#8220; button_border_color__hover=&#8220;#000000&#8243; button_text_color__hover_enabled=&#8220;on|hover&#8220; button_text_color__hover=&#8220;#FFFFFF&#8220;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]Pilates Studio Lilyfit je prvi Klasi\u010dni Pilates Studio u Beogradu, sme\u0161ten u prelepom kraju Senjaka. Nudimo najbolje \u010dasove Klasi\u010dnog Pilatesa u privatnim i malim grupnim treninzima pod vo\u0111stvom na\u0161ih odli\u010dnih trenera.<br \/>\nPosve\u0107eni smo podu\u010davanju Klasi\u010dnog Pilatesa, pravog dela D\u017eozefa Pilatesa zvanog Kontrologija. Mi smo uto\u010di\u0161te za Pilates po\u010detnike, kao i za fitness entuzijaste, profesionalne sportiste i sve izme\u0111u. U Pilates Studiju Lilyfit otkri\u0107e\u0161 koliko se dobro ose\u0107a\u0161 rade\u0107i pravi Pilates, i zajednicu gde se svako na svakom nivou podr\u017eava. Pilates Studio Lilyfit je opremljen Kontrologija opremom od Balanced Body kao i Legacy Pilates spravama.[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_line_height=&#8220;1.4em&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 style=\"text-align: center;\"><span>&#8222;Ose\u0107a\u0107e\u0161 se bolje nakon deset \u010dasova, izgleda\u0107e\u0161 bolje nakon dvadeset \u010dasova, a ima\u0107e\u0161 potpuno novo telo nakon trideset \u010dasova.&#8220;<b><br \/>\n<\/b><\/span><\/h2>\n<div style=\"text-align: center;\"><span><b> <\/b><\/span><\/div>\n<div>\n<p style=\"text-align: center;\"><span><b><\/b><\/span><\/p>\n<div class=\"pilates-quote\" style=\"text-align: right;\">D\u017eozef Pilates<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||15px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Gotham-Book|500|||||||&#8220; header_font_size=&#8220;44px&#8220; header_line_height=&#8220;1.2em&#8220; custom_margin=&#8220;15px||15px||true|false&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;12px||12px||false|false&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220; custom_padding_last_edited=&#8220;off|phone&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;38px&#8220; header_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; header_letter_spacing__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<h1 style=\"text-align: center;\">\u010casovi u Lilyfit Studiju<\/h1>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#aac6be&#8220; divider_weight=&#8220;8px&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;350px&#8220; max_width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; make_equal=&#8220;on&#8220; module_class=&#8220;lf-what-moves&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; module_class=&#8220;new-studio-first-box&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;||25px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_css_main_element=&#8220;padding: 2rem;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"three-sections-section new-studio\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3 style=\"color:white;\"><span>1:1 Privatni \u010dasovi<\/span><\/h3>\n<p><!-- [et_pb_line_break_holder] -->  <picture><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/1-1-class.webp\" type=\"image\/webp\"><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/1-1-class.jpg\" type=\"image\/jpeg\"><!-- [et_pb_line_break_holder] -->  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/08\/1-1-class.jpg\" alt=\"Pilates na strunja\u010di za po\u010detnike\"><!-- [et_pb_line_break_holder] --><\/source><\/source><\/picture><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/h3>\n<h5 class=\"three-sections-under-title\" style=\"color:white;\"><!-- [et_pb_line_break_holder] -->1:1 \u010das je osmi\u0161ljen za pojedince koji su novi u Pilatesu ili one kojima je potrebna personalizovana pa\u017enja da bi postigli svoje fitness ciljeve. \u010casovi su prilago\u0111eni tvom specifi\u010dnom nivou iskustva u Pilatesu. Tokom \u010dasa, instruktor \u0107e te voditi kroz klasi\u010dnu Pilates Metodu, koja se fokusira na ja\u010danje, istezanje, toniranje, pove\u0107anje fleksibilnosti i smanjenje stresa.<!-- [et_pb_line_break_holder] --><\/h5>\n<p><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; module_class=&#8220;new-studio-second-box&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;||25px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_css_main_element=&#8220;||padding: 2rem;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"three-sections-section new-studio\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<h3><span>Grupni \u010dasovi<\/span><!-- [et_pb_line_break_holder] --><\/h3>\n<p><!-- [et_pb_line_break_holder] -->  <picture><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/joes-gym.webp\" type=\"image\/webp\"><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/joes-gym.jpg\"><!-- [et_pb_line_break_holder] -->  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/08\/joes-gym.jpg\" alt=\"Pilates na strunja\u010di srednji\/napredni nivo\"><!-- [et_pb_line_break_holder] --><\/source><\/source><\/picture><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<h5 class=\"three-sections-under-title\"><!-- [et_pb_line_break_holder] -->Joe&#8217;s Gym &#8211; &#8216;D\u017eoova Teretana&#8217; na\u0161i grupni \u010dasovi su savr\u0161eni za one sa iskustvom u Pilates repertoaru. Ovi \u010dasovi nude efikasnu i pristupa\u010dnu alternativu Privatnim Pilates \u010dasovima, a istovremeno pru\u017eaju personalizovanu pa\u017enju i brigu. Ve\u017ebanje sa prijateljima mo\u017ee stvoriti motivi\u0161u\u0107e i podr\u017eavaju\u0107e okru\u017eenje, pove\u0107avaju\u0107i u\u017eivanje u tvojim treninzima. Da bi se pridru\u017eili na\u0161im grupnim \u010dasovima D\u017eoova Teretana, potrebno je da imate odradjena 4 Privatna \u010dasa.<\/h5>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; module_class=&#8220;new-studio-third-box&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;padding: 2rem;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"three-sections-section new-studio\"><!-- [et_pb_line_break_holder] --><\/p>\n<h3><span>Virtuelni \u010dasovi<\/span><\/h3>\n<p><!-- [et_pb_line_break_holder] --><picture><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/virtual.webp\" type=\"image\/webp\"><!-- [et_pb_line_break_holder] --><source srcset=\"\/wp-content\/uploads\/2024\/08\/virtual.jpg\"><!-- [et_pb_line_break_holder] -->  <img decoding=\"async\" src=\"\/wp-content\/uploads\/2024\/08\/virtual.jpg\" alt=\"Istezanje - Svi nivoi\"><!-- [et_pb_line_break_holder] --><\/source><\/source><\/picture><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<h5 class=\"three-sections-under-title\"><!-- [et_pb_line_break_holder] -->Iskusi prednosti Pilatesa bez obzira gde se nalazi\u0161 sa na\u0161im virtuelnim Privatnim 1:1 Pilates \u010dasovima prilago\u0111enim za one koji ne sti\u017eu da do\u0111u u studio, putnike i osobe koje \u017eive van dr\u017eave. Pridru\u017ei se na\u0161im live online \u010dasovima koje vode iskusni instruktori, omogu\u0107avaju\u0107i ti da odr\u017eava\u0161 svoju Pilates praksu. Ostani fleksibilan, i mentalno i fizi\u010dki, od ku\u0107e ili dok putuje\u0161 ili boravi\u0161 daleko od ku\u0107e sa na\u0161im pristupa\u010dnim i zanimljivim virtuelnim pilates \u010dasovima.<!-- [et_pb_line_break_holder] --><\/h5>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;10px||0px||false|false&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;0px||0px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_font=&#8220;Gotham-Book|500|||||||&#8220; header_font_size=&#8220;44px&#8220; header_line_height=&#8220;1.2em&#8220; header_2_font_size=&#8220;32px&#8220; header_2_line_height=&#8220;1.3em&#8220; custom_margin=&#8220;15px||15px||true|false&#8220; custom_margin_tablet=&#8220;&#8220; custom_margin_phone=&#8220;12px||12px||false|false&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220; custom_padding_last_edited=&#8220;off|phone&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;38px&#8220; header_font_size_last_edited=&#8220;on|desktop&#8220; header_2_font_size_tablet=&#8220;32px&#8220; header_2_font_size_phone=&#8220;26px&#8220; header_2_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; header_letter_spacing__hover_enabled=&#8220;on|desktop&#8220;]<\/p>\n<h2 style=\"text-align: center;\">Joe&#8217;s Gym &#8211; Originalna Pilates Metoda:<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#aac6be&#8220; divider_weight=&#8220;8px&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;350px&#8220; max_width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code disabled_on=&#8220;on|off|off&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin:auto;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"video-fix\"><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><iframe loading=\"lazy\" width=\"900\" height=\"500\" src=\"https:\/\/www.youtube.com\/embed\/5mKcvTChl_I?si=7xavDZmmlSmKI4ce\" title=\"YouTube video plejer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe><\/div>\n<p>[\/et_pb_code][et_pb_code disabled_on=&#8220;off|on|on&#8220; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin:auto;&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"video-fix\"><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><iframe loading=\"lazy\" width=\"400\" height=\"250\" src=\"https:\/\/www.youtube.com\/embed\/5mKcvTChl_I?si=7xavDZmmlSmKI4ce\" title=\"YouTube video plejer\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;25px||||false|false&#8220; custom_css_main_element=&#8220;display: none&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;2_5,3_5&#8243; make_equal=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; module_alignment_tablet=&#8220;&#8220; module_alignment_phone=&#8220;center&#8220; module_alignment_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin: auto&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Gotham-Book||||||||&#8220; text_font_size=&#8220;18px&#8220; text_line_height=&#8220;1.8em&#8220; header_2_font=&#8220;Cera-Black||||||||&#8220; header_2_font_size=&#8220;42px&#8220; header_2_line_height=&#8220;1.2em&#8220; header_2_font_size_tablet=&#8220;&#8220; header_2_font_size_phone=&#8220;30px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 class=\"explore-title\"><span>GDE I KADA TI ODGOVARA<\/span><\/h2>\n<p style=\"margin-bottom: .4em;\"><span>Pridru\u017ei se na\u0161im \u010dasovima u\u017eivo i upoznaj na\u0161u me\u0111unarodnu zajednicu. Povezujemo se na strunja\u010di gde god da si na svetu.  <\/span><\/p>\n<p><a href=\"#\" class=\"button-home\">Pogledaj raspored<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/lilyfit.com\/wp-content\/uploads\/2021\/11\/video-schedule.webp&#8220; title_text=&#8220;video-raspored&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;10px||0px||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243; admin_label=&#8220;Testimonials&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code module_class=&#8220;community-part&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"title-story-2\"><span>\u0160ta na\u0161i klijenti ka\u017eu:<\/span><\/div>\n<p><!-- [et_pb_line_break_holder] -->[\/et_pb_code][et_pb_code _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<div class=\"owl-carousel\"><!-- [et_pb_line_break_holder] -->    <\/p>\n<div class=\"item\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/01\/emma-tomes.jpg\"><\/p>\n<div class=\"client-content\"><!-- [et_pb_line_break_holder] -->Preselila sam se u Beograd jer moj mu\u017e ima ovde postavljenje. \u017delela sam da po\u010dnem sa pilatesom i tako sam sre\u0107na \u0161to sam prona\u0161la Lilyfit! Moja prva sesija je bila fantasti\u010dna jer smo se odmah uklopile. Lily je znala \u0161ta \u017eelim i koliko mogu da se pomerim. Radim pilates 9 godina i imala sam 3 neverovatna u\u010ditelja. Lily je neverovatna u svom podu\u010davanju i razumevanju metode. U\u010dim nove stvari na svakoj sesiji i kontinuirano pobolj\u0161avam svoju snagu i fleksibilnost. Radim 2-3 sesije nedeljno i ve\u0107 vidim napredak. Lily je fantasti\u010dna u\u010diteljica i toplo bih je preporu\u010dila!        <!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"client-name\"><span>Emma Tomes<\/span><\/div>\n<p><!-- [et_pb_line_break_holder] -->      <\/div>\n<\/div>\n<p><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"item\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/01\/ivana-kahrmann.jpg\"><\/p>\n<div class=\"client-content\"><!-- [et_pb_line_break_holder] -->Po\u010dela sam 1:1 pilates sesije sa Lily pre oko tri meseca. Njen profesionalizam i fokus na svaki pokret i dr\u017eanje tela tokom ve\u017ebanja, pomogli su mi da oblikujem svoje telo na na\u010din koji sam oduvek \u017eelela &#8211; bez ogromnih mi\u0161i\u0107a bodibildera, ve\u0107 lepo oblikovano, vitko telo. Lily je ispravila moje dr\u017eanje i nau\u010dila me kako da pobolj\u0161am tehniku disanja, kao i strpljenju koje pilates u\u010di. Kona\u010dno sam prona\u0161la savr\u0161en trening i ako neko \u017eeli brze i vidljive rezultate, toplo preporu\u010dujem Lilyfit Pilates! Da li sam spomenula da sam uspela da izgubim 4 kilograma? Dala sam vam jo\u0161 jedan razlog da se pridru\u017eite armiji pilates obo\u017eavatelja.     <!-- [et_pb_line_break_holder] -->      <\/p>\n<div class=\"client-name\"><span>Ivana Kahrmann<\/span><\/div>\n<p><!-- [et_pb_line_break_holder] -->      <\/div>\n<\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->   <!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->    <\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dobrodo\u0161li u pilates studio lilyfitPrvi Klasi\u010dni Pilates Studio u BeograduPilates Studio Lilyfit je prvi Klasi\u010dni Pilates Studio u Beogradu, sme\u0161ten u prelepom kraju Senjaka. Nudimo najbolje \u010dasove Klasi\u010dnog Pilatesa u privatnim i malim grupnim treninzima pod vo\u0111stvom na\u0161ih odli\u010dnih trenera. Posve\u0107eni smo podu\u010davanju Klasi\u010dnog Pilatesa, pravog dela D\u017eozefa Pilatesa zvanog Kontrologija. Mi smo uto\u010di\u0161te za [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4191,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-4190","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Studio - LilyFit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lilyfit.com\/sr\/studio\/\" \/>\n<meta property=\"og:locale\" content=\"sr_RS\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Studio - LilyFit\" \/>\n<meta property=\"og:description\" content=\"Dobrodo\u0161li u pilates studio lilyfitPrvi Klasi\u010dni Pilates Studio u BeograduPilates Studio Lilyfit je prvi Klasi\u010dni Pilates Studio u Beogradu, sme\u0161ten u prelepom kraju Senjaka. Nudimo najbolje \u010dasove Klasi\u010dnog Pilatesa u privatnim i malim grupnim treninzima pod vo\u0111stvom na\u0161ih odli\u010dnih trenera. Posve\u0107eni smo podu\u010davanju Klasi\u010dnog Pilatesa, pravog dela D\u017eozefa Pilatesa zvanog Kontrologija. Mi smo uto\u010di\u0161te za [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lilyfit.com\/sr\/studio\/\" \/>\n<meta property=\"og:site_name\" content=\"LilyFit\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T09:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lilyfit.com\/wp-content\/uploads\/2021\/12\/proba-studio-1024x304.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/lilyfit.com\/wp-content\/uploads\/2021\/12\/proba-studio-1024x304.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u043e\u0446\u0435\u045a\u0435\u043d\u043e \u0432\u0440\u0435\u043c\u0435 \u0447\u0438\u0442\u0430\u045a\u0430\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/\",\"url\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/\",\"name\":\"Studio - LilyFit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lilyfit.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/slide-2.jpg\",\"datePublished\":\"2021-09-08T20:13:39+00:00\",\"dateModified\":\"2025-11-04T09:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/#breadcrumb\"},\"inLanguage\":\"sr-RS\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sr-RS\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lilyfit.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/slide-2.jpg\",\"contentUrl\":\"https:\\\/\\\/lilyfit.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/slide-2.jpg\",\"width\":1920,\"height\":745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/studio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Studio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#website\",\"url\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/\",\"name\":\"LilyFit\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sr-RS\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#organization\",\"name\":\"LilyFit\",\"url\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sr-RS\",\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lilyfit.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/slider-1-home.webp\",\"contentUrl\":\"https:\\\/\\\/lilyfit.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/slider-1-home.webp\",\"width\":1920,\"height\":700,\"caption\":\"LilyFit\"},\"image\":{\"@id\":\"https:\\\/\\\/lilyfit.com\\\/sr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Studio - LilyFit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lilyfit.com\/sr\/studio\/","og_locale":"sr_RS","og_type":"article","og_title":"Studio - LilyFit","og_description":"Dobrodo\u0161li u pilates studio lilyfitPrvi Klasi\u010dni Pilates Studio u BeograduPilates Studio Lilyfit je prvi Klasi\u010dni Pilates Studio u Beogradu, sme\u0161ten u prelepom kraju Senjaka. Nudimo najbolje \u010dasove Klasi\u010dnog Pilatesa u privatnim i malim grupnim treninzima pod vo\u0111stvom na\u0161ih odli\u010dnih trenera. Posve\u0107eni smo podu\u010davanju Klasi\u010dnog Pilatesa, pravog dela D\u017eozefa Pilatesa zvanog Kontrologija. Mi smo uto\u010di\u0161te za [&hellip;]","og_url":"https:\/\/lilyfit.com\/sr\/studio\/","og_site_name":"LilyFit","article_modified_time":"2025-11-04T09:27:35+00:00","og_image":[{"url":"https:\/\/lilyfit.com\/wp-content\/uploads\/2021\/12\/proba-studio-1024x304.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/lilyfit.com\/wp-content\/uploads\/2021\/12\/proba-studio-1024x304.jpg","twitter_misc":{"\u041f\u0440\u043e\u0446\u0435\u045a\u0435\u043d\u043e \u0432\u0440\u0435\u043c\u0435 \u0447\u0438\u0442\u0430\u045a\u0430":"12 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lilyfit.com\/sr\/studio\/","url":"https:\/\/lilyfit.com\/sr\/studio\/","name":"Studio - LilyFit","isPartOf":{"@id":"https:\/\/lilyfit.com\/sr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lilyfit.com\/sr\/studio\/#primaryimage"},"image":{"@id":"https:\/\/lilyfit.com\/sr\/studio\/#primaryimage"},"thumbnailUrl":"https:\/\/lilyfit.com\/wp-content\/uploads\/2024\/08\/slide-2.jpg","datePublished":"2021-09-08T20:13:39+00:00","dateModified":"2025-11-04T09:27:35+00:00","breadcrumb":{"@id":"https:\/\/lilyfit.com\/sr\/studio\/#breadcrumb"},"inLanguage":"sr-RS","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lilyfit.com\/sr\/studio\/"]}]},{"@type":"ImageObject","inLanguage":"sr-RS","@id":"https:\/\/lilyfit.com\/sr\/studio\/#primaryimage","url":"https:\/\/lilyfit.com\/wp-content\/uploads\/2024\/08\/slide-2.jpg","contentUrl":"https:\/\/lilyfit.com\/wp-content\/uploads\/2024\/08\/slide-2.jpg","width":1920,"height":745},{"@type":"BreadcrumbList","@id":"https:\/\/lilyfit.com\/sr\/studio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lilyfit.com\/sr\/"},{"@type":"ListItem","position":2,"name":"Studio"}]},{"@type":"WebSite","@id":"https:\/\/lilyfit.com\/sr\/#website","url":"https:\/\/lilyfit.com\/sr\/","name":"LilyFit","description":"","publisher":{"@id":"https:\/\/lilyfit.com\/sr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lilyfit.com\/sr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sr-RS"},{"@type":"Organization","@id":"https:\/\/lilyfit.com\/sr\/#organization","name":"LilyFit","url":"https:\/\/lilyfit.com\/sr\/","logo":{"@type":"ImageObject","inLanguage":"sr-RS","@id":"https:\/\/lilyfit.com\/sr\/#\/schema\/logo\/image\/","url":"https:\/\/lilyfit.com\/wp-content\/uploads\/2022\/09\/slider-1-home.webp","contentUrl":"https:\/\/lilyfit.com\/wp-content\/uploads\/2022\/09\/slider-1-home.webp","width":1920,"height":700,"caption":"LilyFit"},"image":{"@id":"https:\/\/lilyfit.com\/sr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/pages\/4190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/comments?post=4190"}],"version-history":[{"count":0,"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/pages\/4190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/media\/4191"}],"wp:attachment":[{"href":"https:\/\/lilyfit.com\/sr\/wp-json\/wp\/v2\/media?parent=4190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}